{"id":1,"date":"2023-03-08T14:30:23","date_gmt":"2023-03-08T14:30:23","guid":{"rendered":"http:\/\/residencemargherita.cambia-marketing.it\/?p=1"},"modified":"2025-01-08T16:54:57","modified_gmt":"2025-01-08T16:54:57","slug":"lux","status":"publish","type":"post","link":"https:\/\/residencehmargherita.it\/en\/lux\/","title":{"rendered":"Lux"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1\" class=\"elementor elementor-1\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2910b03 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2910b03\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4557fc5\" data-id=\"4557fc5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0f6f37 elementor-widget elementor-widget-heading\" data-id=\"d0f6f37\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lux Apartment<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a706408 elementor-section-full_width elementor-section-height-min-height elementor-section-items-bottom elementor-section-height-default\" data-id=\"a706408\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/LUX.mp4&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted elementor-html5-video\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6d4e3b3\" data-id=\"6d4e3b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-738770d elementor-align-center elementor-widget__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"738770d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/wp-content\/uploads\/2023\/04\/LUX.mp4\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Watch the Video<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c3a368 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5c3a368\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f806918\" data-id=\"f806918\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-106653e elementor-icon-list--layout-inline elementor-align-left elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"106653e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Starting from<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"136.245\" height=\"1\" viewbox=\"0 0 136.245 1\"><path id=\"Tracciato_7\" data-name=\"Tracciato 7\" d=\"M275,1656H411.245\" transform=\"translate(-275 -1655.5)\" fill=\"none\" stroke=\"#eabf47\" stroke-width=\"1\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u20ac 720<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40781e6 elementor-widget elementor-widget-heading\" data-id=\"40781e6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Features<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3be5fd8 elementor-widget elementor-widget-heading\" data-id=\"3be5fd8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">mETRATURE - 40 mq <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a545d8 elementor-widget elementor-widget-heading\" data-id=\"4a545d8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Accomodates<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0b63ae elementor-widget elementor-widget-text-editor\" data-id=\"b0b63ae\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Accomodates 4 people:<\/p><p>- 1 Double bed<\/p><p>- 2 Single bunk beds<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e223a7f elementor-widget elementor-widget-heading\" data-id=\"e223a7f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Equipment<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b837d44 elementor-widget elementor-widget-text-editor\" data-id=\"b837d44\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Cucina attrezzata di tutti gli accessori, compreso forno | frigo 300 LT | Lavastoviglie |\u00a0 una zona living con salotto e TV\u00a0 smart | Wi-fi gratuito | Aria condizionata | Zanzariere | Riscaldamento | Cassetta di sicurezza | Balcone 15mq con tavolo, sedie e sdraio<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4706306\" data-id=\"4706306\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9bb847c elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"9bb847c\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 12\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9bb847c\" data-elementor-lightbox-title=\"Residence Margherita a Montalto Marina camera LUX\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTIzMSwidXJsIjoiaHR0cHM6XC9cL3Jlc2lkZW5jZWhtYXJnaGVyaXRhLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wM1wvTFVYLTEuanBnIiwic2xpZGVzaG93IjoiOWJiODQ3YyJ9\" href=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-1.jpg\" alt=\"Residence Margherita a Montalto Marina camera LUX\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 12\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9bb847c\" data-elementor-lightbox-title=\"Residence Margherita a Montalto Marina camera LUX\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTIzMiwidXJsIjoiaHR0cHM6XC9cL3Jlc2lkZW5jZWhtYXJnaGVyaXRhLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wM1wvTFVYLTIuanBnIiwic2xpZGVzaG93IjoiOWJiODQ3YyJ9\" href=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-2.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-2.jpg\" alt=\"Residence Margherita a Montalto Marina camera LUX\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 12\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9bb847c\" data-elementor-lightbox-title=\"Residence Margherita a Montalto Marina camera LUX\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTIzMywidXJsIjoiaHR0cHM6XC9cL3Jlc2lkZW5jZWhtYXJnaGVyaXRhLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wM1wvTFVYLTMuanBnIiwic2xpZGVzaG93IjoiOWJiODQ3YyJ9\" href=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-3.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-3.jpg\" alt=\"Residence Margherita a Montalto Marina camera LUX\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 12\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9bb847c\" data-elementor-lightbox-title=\"Residence Margherita a Montalto Marina camera LUX\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTIzNCwidXJsIjoiaHR0cHM6XC9cL3Jlc2lkZW5jZWhtYXJnaGVyaXRhLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wM1wvTFVYLTQuanBnIiwic2xpZGVzaG93IjoiOWJiODQ3YyJ9\" href=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-4.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-4.jpg\" alt=\"Residence Margherita a Montalto Marina camera LUX\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 12\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9bb847c\" data-elementor-lightbox-title=\"Residence Margherita a Montalto Marina camera LUX\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTIzNSwidXJsIjoiaHR0cHM6XC9cL3Jlc2lkZW5jZWhtYXJnaGVyaXRhLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wM1wvTFVYLTUuanBnIiwic2xpZGVzaG93IjoiOWJiODQ3YyJ9\" href=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-5.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-5.jpg\" alt=\"Residence Margherita a Montalto Marina camera LUX\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 12\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9bb847c\" data-elementor-lightbox-title=\"Residence Margherita a Montalto Marina camera LUX\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTIzNiwidXJsIjoiaHR0cHM6XC9cL3Jlc2lkZW5jZWhtYXJnaGVyaXRhLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wM1wvTFVYLTYuanBnIiwic2xpZGVzaG93IjoiOWJiODQ3YyJ9\" href=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-6.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-6.jpg\" alt=\"Residence Margherita a Montalto Marina camera LUX\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 12\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9bb847c\" data-elementor-lightbox-title=\"Residence Margherita a Montalto Marina camera LUX\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTIzNywidXJsIjoiaHR0cHM6XC9cL3Jlc2lkZW5jZWhtYXJnaGVyaXRhLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wM1wvTFVYLTcuanBnIiwic2xpZGVzaG93IjoiOWJiODQ3YyJ9\" href=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-7.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-7.jpg\" alt=\"Residence Margherita a Montalto Marina camera LUX\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 12\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9bb847c\" data-elementor-lightbox-title=\"Residence Margherita a Montalto Marina camera LUX\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTIzOCwidXJsIjoiaHR0cHM6XC9cL3Jlc2lkZW5jZWhtYXJnaGVyaXRhLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wM1wvTFVYLTguanBnIiwic2xpZGVzaG93IjoiOWJiODQ3YyJ9\" href=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-8.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-8.jpg\" alt=\"Residence Margherita a Montalto Marina camera LUX\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 12\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9bb847c\" data-elementor-lightbox-title=\"Residence Margherita a Montalto Marina camera LUX\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTIzOSwidXJsIjoiaHR0cHM6XC9cL3Jlc2lkZW5jZWhtYXJnaGVyaXRhLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wM1wvTFVYLTkuanBnIiwic2xpZGVzaG93IjoiOWJiODQ3YyJ9\" href=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-9.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-9.jpg\" alt=\"Residence Margherita a Montalto Marina camera LUX\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 12\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9bb847c\" data-elementor-lightbox-title=\"Residence Margherita a Montalto Marina camera LUX\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI0MCwidXJsIjoiaHR0cHM6XC9cL3Jlc2lkZW5jZWhtYXJnaGVyaXRhLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wM1wvTFVYLTEwLmpwZyIsInNsaWRlc2hvdyI6IjliYjg0N2MifQ%3D%3D\" href=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-10.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-10.jpg\" alt=\"Residence Margherita a Montalto Marina camera LUX\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 12\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9bb847c\" data-elementor-lightbox-title=\"Residence Margherita a Montalto Marina camera LUX\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI0MSwidXJsIjoiaHR0cHM6XC9cL3Jlc2lkZW5jZWhtYXJnaGVyaXRhLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wM1wvTFVYLTExLmpwZyIsInNsaWRlc2hvdyI6IjliYjg0N2MifQ%3D%3D\" href=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-11.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-11.jpg\" alt=\"Residence Margherita a Montalto Marina camera LUX\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 12\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9bb847c\" data-elementor-lightbox-title=\"Residence Margherita a Montalto Marina camera LUX\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTI0MiwidXJsIjoiaHR0cHM6XC9cL3Jlc2lkZW5jZWhtYXJnaGVyaXRhLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wM1wvTFVYLTEyLmpwZyIsInNsaWRlc2hvdyI6IjliYjg0N2MifQ%3D%3D\" href=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-12.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/residencehmargherita.it\/wp-content\/uploads\/2023\/03\/LUX-12.jpg\" alt=\"Residence Margherita a Montalto Marina\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5b1ed4 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor--h-position-center elementor--v-position-middle elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"e5b1ed4\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-f59c0ed swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-1265adf swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-d7c6041 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-7d0d47e swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-a752ab7 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-093bbda swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-ef6a548 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-2d7b34a swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-b895f26 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-bf30665 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-0fb34f3 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-5561360 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a16ad58 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a16ad58\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-258918c\" data-id=\"258918c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5db9a4 elementor-widget elementor-widget-spacer\" data-id=\"a5db9a4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8a01a41\" data-id=\"8a01a41\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f402a60 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f402a60\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c66a54\" data-id=\"2c66a54\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b08e98d elementor-widget elementor-widget-heading\" data-id=\"b08e98d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Discover also the other appartments<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c2a91d3 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c2a91d3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6400f69\" data-id=\"6400f69\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ff4085 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"8ff4085\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Superior Apartment<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66b9691 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"66b9691\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/residencehmargherita.it\/en\/superior\/\">Discover<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3eb3d7a\" data-id=\"3eb3d7a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a75d27f elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"a75d27f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/residencehmargherita.it\/en\/lux\/\">Standard Apartment<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d67f0c9 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"d67f0c9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/residencehmargherita.it\/en\/standard\/\">Discover<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-527141d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"527141d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e2bf997\" data-id=\"e2bf997\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1397cf4 elementor-widget elementor-widget-heading\" data-id=\"1397cf4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">request information<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b1341f elementor-button-align-end elementor-widget elementor-widget-form\" data-id=\"4b1341f\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Successivo&quot;,&quot;step_previous_label&quot;:&quot;Precedente&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Nuovo modulo\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"1\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"4b1341f\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-33\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Name\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-33 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tE-mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"E-mail\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_57cee6b elementor-col-33 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_57cee6b\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tMobile phone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_57cee6b]\" id=\"form-field-field_57cee6b\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Mobile phone number\" required=\"required\" aria-required=\"true\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-number elementor-field-group elementor-column elementor-field-group-field_02a662d elementor-col-33 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_02a662d\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNumber of adults\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t<input type=\"number\" name=\"form_fields[field_02a662d]\" id=\"form-field-field_02a662d\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Enter number of adults\" required=\"required\" aria-required=\"true\" min=\"\" max=\"\" >\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-number elementor-field-group elementor-column elementor-field-group-field_21ffd3d elementor-col-33 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_21ffd3d\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNumber of Children\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t<input type=\"number\" name=\"form_fields[field_21ffd3d]\" id=\"form-field-field_21ffd3d\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Enter number of children\" required=\"required\" aria-required=\"true\" min=\"\" max=\"\" >\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_6b19949 elementor-col-33 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_6b19949\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tChildren's ages\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_6b19949]\" id=\"form-field-field_6b19949\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Children&#039;s ages\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-date elementor-field-group elementor-column elementor-field-group-field_658a494 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_658a494\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tDate of arrival \t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\n\t\t<input type=\"date\" name=\"form_fields[field_658a494]\" id=\"form-field-field_658a494\" class=\"elementor-field elementor-size-sm  elementor-field-textual elementor-date-field\" placeholder=\"Enter arrival date\" required=\"required\" aria-required=\"true\" pattern=\"[0-9]{4}-[0-9]{2}-[0-9]{2}\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-date elementor-field-group elementor-column elementor-field-group-field_0a72e1f elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_0a72e1f\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tDeparture date \t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\n\t\t<input type=\"date\" name=\"form_fields[field_0a72e1f]\" id=\"form-field-field_0a72e1f\" class=\"elementor-field elementor-size-sm  elementor-field-textual elementor-date-field\" placeholder=\"Enter date of departure\" required=\"required\" aria-required=\"true\" pattern=\"[0-9]{4}-[0-9]{2}-[0-9]{2}\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tMessage\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Message\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_923013c elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_923013c]\" id=\"form-field-field_923013c\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\" required=\"required\" aria-required=\"true\">\n\t\t\t\t<label for=\"form-field-field_923013c\">I have read and accept the <a style=\"color:#000\" href=\"https:\/\/residencehmargherita.it\/en\/privacy-policy\/\"> privacy policy<\/a><\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_4d8eb67 elementor-col-100 recaptcha_v3-bottomright\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_4d8eb67\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LfN4rEqAAAAAIW4MZS6UF1F5-yrTNGk38RK7kAF\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomright\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">send a request<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Appartamento Lux Guarda il Video A partire da \u20ac 720 Caratteristiche mETRATURA &#8211; 40 mq posti letto 4 Posti letto: &#8211; 1 Letto matrimoniale &#8211; 2 Letti singoli a castello Dotazioni Cucina attrezzata di tutti gli accessori, compreso forno | frigo 300 LT | Lavastoviglie |\u00a0 una zona living con salotto e TV\u00a0 smart | [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/residencehmargherita.it\/en\/wp-json\/wp\/v2\/posts\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/residencehmargherita.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/residencehmargherita.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/residencehmargherita.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/residencehmargherita.it\/en\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":95,"href":"https:\/\/residencehmargherita.it\/en\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"predecessor-version":[{"id":1514,"href":"https:\/\/residencehmargherita.it\/en\/wp-json\/wp\/v2\/posts\/1\/revisions\/1514"}],"wp:attachment":[{"href":"https:\/\/residencehmargherita.it\/en\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/residencehmargherita.it\/en\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/residencehmargherita.it\/en\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}